{"id":995,"date":"2012-01-19T11:50:40","date_gmt":"2012-01-19T10:50:40","guid":{"rendered":"http:\/\/rt.boullier.fr\/?p=995"},"modified":"2012-01-19T11:50:40","modified_gmt":"2012-01-19T10:50:40","slug":"art995","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2012\/01\/19\/art995\/","title":{"rendered":"Monsieur le Juge&#8230;."},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"font-size: 18px;\"><strong><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18px;\"><strong><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18px;\"><strong><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size:18px;\"><strong>Monsieur le juge<\/strong><\/span>&#8230;.<\/p>\n<p>Ce mercredi de d\u00e9cembre, dans la salle d&rsquo;audience du tribunal administratif de Marseille, une fois de plus nous attendions votre verdict. Nous, c&rsquo;est-\u00e0-dire deux citoyens militants d&rsquo;un \u00e2ge certain et un peu durs d&rsquo;oreille. Nous n&rsquo;\u00e9tions pas l\u00e0 par hasard mais en t\u00e9moins qui se sont sentis outrag\u00e9s par le fonctionnement d&rsquo;une justice aux ordres du pouvoir.<\/p>\n<p>Au fond de la salle, apeur\u00e9s et d\u00e9sempar\u00e9s, trois femmes dont l&rsquo;une allaite son petit et un homme. A leur c\u00f4t\u00e9 un octog\u00e9naire, pasteur protestant, un peu perdu lui aussi, qui tente de comprendre et de rassurer la famille qu&rsquo;il a accompagn\u00e9e dans cette gal\u00e8re. Ce sont des Rroms Roumains qui expuls\u00e9s de squat en squat ont trouv\u00e9 provisoirement un petit coin dans un parking d&rsquo;une halte de gare pour y construire un abri de fortune et subsister avec l&rsquo;aide de quelques voisins et des restos du coeur. Ils ont entre leurs mains un \u00e9pais dossier de convocation et la plainte de la SNCF qui exige leur expulsion sous pr\u00e9texte d&rsquo;ins\u00e9curit\u00e9 et de l&rsquo;insalubrit\u00e9. Manifestement ils n&rsquo;ont pas su lire ce dossier et ne parlent pas le fran\u00e7ais. Bref le r\u00e9gime habituel des convocations devant ce tribunal qui applique sans sourciller les plus r\u00e9centes directives gouvernementales &lsquo;en faveur&rsquo; des Rroms. <\/p>\n<p>Trois autres personnes, bien fran\u00e7aises celles-l\u00e0, viennent d&rsquo;entrer discr\u00e8tement et sont tout aussi intimid\u00e9es. Nous avions rendez-vous. J&rsquo;avais \u00e9t\u00e9 pr\u00e9venu la veille de leur convocation devant le juge sur plainte du maire de la commune dans laquelle ces &lsquo;gens du voyage&rsquo; stationnent avec leurs caravanes depuis quelques semaines. Dans ces conditions, pas le temps de faire appel \u00e0 un avocat (et puis \u00e7a co\u00fbte cher) alors je suis l\u00e0 pour tenter de comprendre leur situation et de plaider leur cause. C&rsquo;est la troisi\u00e8me fois en six semaines qu&rsquo;ils sont ainsi convoqu\u00e9s pour les m\u00eames raisons. Selon le maire, ils stationnent ill\u00e9galement sur un espace public communal et cr\u00e9ent de multiples troubles \u00e0 l&rsquo;ordre public&nbsp;: \u00ab&nbsp;<em>Or le maire ne peut accepter que la s\u00e9curit\u00e9 des personnes soit mise en cause sur le territoire de sa Commune&#8230;&nbsp;Le maire ne peut accepter que sa responsabilit\u00e9 soit engag\u00e9e par des occupants ill\u00e9gaux qui ont fait l&rsquo;objet de plusieurs ordonnances d&rsquo;expulsion&nbsp;\u00bb<\/em><\/p>\n<p>En effet&nbsp;: par deux fois d\u00e9j\u00e0 le m\u00eame juge a ordonn\u00e9 l&rsquo;expulsion de ces familles et elles se sont ex\u00e9cut\u00e9es. J&rsquo;avais pourtant pu intervenir au nom de l&rsquo;association Rencontres Tsiganes en rappelant la loi du 5\/7\/2000 qui pr\u00e9voit la r\u00e9alisation des aires d&rsquo;accueil pour les gens du voyage et en pr\u00e9cisant que la commune concern\u00e9e ne s&rsquo;\u00e9tant pas acquitt\u00e9e de son obligation ne pouvait s&rsquo;en pr\u00e9valoir pour demander cette expulsion. \u00ab&nbsp;Merci Monsieur le pr\u00e9sident d&rsquo;avoir bien voulu accepter de m&rsquo;entendre une nouvelle fois malgr\u00e9 ma maladresse et mon incomp\u00e9tence&nbsp;!!. Vous auriez pu aussi revoir votre dossier, relire les textes de lois et la jurisprudence et, sans vous apitoyer sur la situation de ces familles, accepter de les entendre et consid\u00e9rer que, dans cette affaire, les torts sont au moins largement partag\u00e9s. Mais que vous soyez puissant ou mis\u00e9rable &#8230;.&nbsp;!!&nbsp;\u00bb<\/p>\n<p>Conclusion&nbsp;: en quelques minutes ce mercredi-l\u00e0, comme d&rsquo;autres jours, sans avocat, sans interpr\u00e8te, quasiment sans t\u00e9moins, un homme, seul d\u00e9tenteur du&nbsp;pouvoir judiciaire, au nom du peuple fran\u00e7ais, a donn\u00e9 \u00e0 ces hommes et ces femmes et \u00e0 nous deux, une image intol\u00e9rable de la justice dans ce pays des Droits de l&rsquo;Homme. Inutile de pr\u00e9ciser qu&rsquo;en 48 heures, dans un cas comme dans l&rsquo;autre, une ordonnance d&rsquo;expulsion a intim\u00e9 l&rsquo;ordre aux familles de quitter les lieux sous peine d&rsquo;une astreinte financi\u00e8re lourde et de menace de recours \u00e0 la force publique.<\/p>\n<p>J&rsquo;imagine les multiples arguments que l&rsquo;on pourra mettre en avant pour condamner ces propos et peut-\u00eatre m\u00eame me poursuivre pour outrage \u00e0 magistrat. Qu&rsquo;importe&nbsp;!!! je n&rsquo;ai fait que r\u00e9sumer une heure pass\u00e9e devant un tribunal de Marseille un certain mercredi noir .<\/p>\n<p>Alain FOUREST<\/p>\n<p>Marseille&nbsp;le 17\/01\/2012 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monsieur le juge&#8230;. Ce mercredi de d\u00e9cembre, dans la salle d&rsquo;audience du tribunal administratif de Marseille, une fois de plus nous attendions votre verdict. Nous, c&rsquo;est-\u00e0-dire deux citoyens militants d&rsquo;un \u00e2ge certain et un peu durs d&rsquo;oreille. Nous n&rsquo;\u00e9tions pas l\u00e0 par hasard mais en t\u00e9moins qui se sont sentis outrag\u00e9s par le fonctionnement d&rsquo;une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,16],"tags":[],"class_list":["post-995","post","type-post","status-publish","format-standard","hentry","category-editos","category-rub82"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=995"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/995\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}