{"id":2602,"date":"2015-06-02T14:27:18","date_gmt":"2015-06-02T13:27:18","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=2602"},"modified":"2015-06-02T14:27:18","modified_gmt":"2015-06-02T13:27:18","slug":"le-maire-de-roquebrune-argens-condamne-en-appel","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2015\/06\/02\/le-maire-de-roquebrune-argens-condamne-en-appel\/","title":{"rendered":"Le maire de Roquebrune \/Argens condamn\u00e9 en appel"},"content":{"rendered":"<p>Apr\u00e8s un incendie survenu dans un campement rom, le maire de Roquebrune-sur-Argens avait l\u00e2ch\u00e9 : \u00abCe qui est presque dommage, c&rsquo;est qu&rsquo;on ait appel\u00e9 trop t\u00f4t les secours.\u00bb La cour d&rsquo;appel d&rsquo;Aix-en-Provence a confirm\u00e9 mardi la condamnation en premi\u00e8re instance pour provocation \u00e0 la haine raciale.<\/p>\n<p>Me Florence Leroux-Ghristi, d\u00e9fenseure de la Ligue des Droits de l&rsquo;homme et du Forum europ\u00e9en des Roms et des gens du voyage, avait assur\u00e9 \u00abfr\u00e9mir sur l&rsquo;impact qu&rsquo;auraient pu avoir ces paroles\u00bb.<\/p>\n<p>Luc Jousse a par ailleurs \u00e9t\u00e9 condamn\u00e9 en appel le 14 avril \u00e0 5 ans d&rsquo;interdiction de droits civiques (et donc d&rsquo;in\u00e9ligibilit\u00e9) et 20.000 euros d&rsquo;amende pour d\u00e9tournement de fonds publics, pour avoir notamment abus\u00e9 de l&rsquo;utilisation de cartes d&rsquo;essence de sa commune. Il a annonc\u00e9 qu&rsquo;il se pourvoie en cassassion et se maintient comme maire.<\/p>\n<p>Est ce un hasard ?<\/p>\n<p>ON connait depuis d\u00e9j\u00e0 longtemps le comportement odieux de ce maire en lutte permanente contre les Roms et les Gens du Voyage. On apprend qu&rsquo;un groupe de voyageurs install\u00e9s sur la commune depuis quelques semaines vient de recevoir d&rsquo;un huissier l&rsquo;ordre de quitter les lieux sous 24h. Les associations et la LDH se mobilisent pour venir en aide \u00e0 ces familles et d\u00e9fendre leurs droits<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un incendie survenu dans un campement rom, le maire de Roquebrune-sur-Argens avait l\u00e2ch\u00e9 : \u00abCe qui est presque dommage, c&rsquo;est qu&rsquo;on ait appel\u00e9 trop t\u00f4t les secours.\u00bb La cour d&rsquo;appel d&rsquo;Aix-en-Provence a confirm\u00e9 mardi la condamnation en premi\u00e8re instance pour provocation \u00e0 la haine raciale. Me Florence Leroux-Ghristi, d\u00e9fenseure de la Ligue des Droits [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[51],"class_list":["post-2602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rub39","tag-discriminations"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/2602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=2602"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/2602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=2602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=2602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}