{"id":1792,"date":"2015-05-30T15:10:18","date_gmt":"2015-05-30T14:10:18","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=1792"},"modified":"2015-05-30T15:10:18","modified_gmt":"2015-05-30T14:10:18","slug":"la-persistance-des-prejuges-anti-roms","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2015\/05\/30\/la-persistance-des-prejuges-anti-roms\/","title":{"rendered":"La persistance des pr\u00e9jug\u00e9s anti-Roms"},"content":{"rendered":"<p>Le chapitre IV du rapport de la CNCDH (Commission Nationale Consultative des Droits de l&rsquo;Homme) est consacr\u00e9 \u00e0 la situation des Roms en France. Une fois de plus ce rapport met en \u00e9vidence que <strong>les Roms sont vus comme les principales victimes du racisme en France. <\/strong><\/p>\n<p>Un peu d&rsquo;espoir cependant qui montre que l&rsquo;action de militants n&rsquo;est pas toujours sans effet sur l&rsquo;opinion : On remarque toutefois que dans le m\u00eame temps la prise de conscience du niveau de discrimination contre les Tsiganes, les Roms et les gens du voyage en France a fortement augment\u00e9, atteignant 16 % en 2014, un petit peu moins qu\u2019en 2013 mais bien plus qu\u2019en 2003. Et le pourcentage de ceux qui estiment qu\u2019on ne parle pas assez de l\u2019extermination des Roms pendant la Seconde Guerre mondiale est mont\u00e9 depuis l\u2019an dernier de 35 % \u00e0 40 %.<\/p>\n<p>L\u2019attention croissante port\u00e9e \u00e0 la discrimination des Tsiganes est le miroir de plusieurs mobilisations qui se sont d\u00e9velopp\u00e9es autour des droits des Roms.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le chapitre IV du rapport de la CNCDH (Commission Nationale Consultative des Droits de l&rsquo;Homme) est consacr\u00e9 \u00e0 la situation des Roms en France. Une fois de plus ce rapport met en \u00e9vidence que les Roms sont vus comme les principales victimes du racisme en France. Un peu d&rsquo;espoir cependant qui montre que l&rsquo;action de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18],"tags":[51],"class_list":["post-1792","post","type-post","status-publish","format-standard","hentry","category-discriminations-racisme","category-migrants-roms","tag-discriminations"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=1792"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1792\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=1792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=1792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=1792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}