{"id":13619,"date":"2018-01-09T14:10:33","date_gmt":"2018-01-09T13:10:33","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=13619"},"modified":"2018-01-09T14:10:33","modified_gmt":"2018-01-09T13:10:33","slug":"en-2018-malgre-les-belles-promesses-ils-dorment-mais-aussi-meurent-encore-dans-la-rue","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2018\/01\/09\/en-2018-malgre-les-belles-promesses-ils-dorment-mais-aussi-meurent-encore-dans-la-rue\/","title":{"rendered":"En 2018, malgr\u00e9 les belles promesses, ils dorment mais aussi meurent encore dans la rue !"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13656 aligncenter\" src=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/Melki-300x200.jpg\" alt=\"\" width=\"447\" height=\"333\" \/><em>@Marc Melki<\/em><\/p>\n<p>Avec la Fondation Abb\u00e9 Pierre, le F\u00e9d\u00e9ration des Acteurs de la Solidarit\u00e9 et la Voix des Rroms, les 45 associations du CNDH Romeurope s&rsquo;adressent au Pr\u00e9sident de la R\u00e9publique pour demander une v\u00e9ritable politique de r\u00e9sorption des bidonvilles et d&rsquo;inclusion de leurs habitants, qui tranche avec la politique \u00ab\u00a0s\u00e9curitaire\u00a0\u00bb d&rsquo;expulsions sans relogement. Vous trouverez la lettre ouverte en pi\u00e8ce-jointe.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13620 aligncenter\" src=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/Lettre-au-pre\u0301sident--212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" \/><\/p>\n<p>&#8230;ils dorment &#8230;et il meurent dans la rue,<\/p>\n<p>Le Monde du 3 janvier 2018 \u00a0\u00bb Sans-abri : un d\u00e9calage entre les annonces du pr\u00e9sident et les faits \u00a0\u00bb \u00e9voque les 407 personnes signal\u00e9es qui sont mortes en 2017 dans la rue en France. Le collectif Les Morts de la rue estime le nombre r\u00e9el cinq \u00e0 six fois plus \u00e9lev\u00e9.<\/p>\n<p>Le CAC 40, \u00e7a va, merci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>@Marc Melki Avec la Fondation Abb\u00e9 Pierre, le F\u00e9d\u00e9ration des Acteurs de la Solidarit\u00e9 et la Voix des Rroms, les 45 associations du CNDH Romeurope s&rsquo;adressent au Pr\u00e9sident de la R\u00e9publique pour demander une v\u00e9ritable politique de r\u00e9sorption des bidonvilles et d&rsquo;inclusion de leurs habitants, qui tranche avec la politique \u00ab\u00a0s\u00e9curitaire\u00a0\u00bb d&rsquo;expulsions sans relogement. Vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,12],"tags":[],"class_list":["post-13619","post","type-post","status-publish","format-standard","hentry","category-communiques-interpellations","category-habitat"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=13619"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13619\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=13619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=13619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=13619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}