{"id":13614,"date":"2018-01-09T14:09:39","date_gmt":"2018-01-09T13:09:39","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=13614"},"modified":"2018-01-09T14:09:39","modified_gmt":"2018-01-09T13:09:39","slug":"2017-un-bilan-en-demi-teinte","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2018\/01\/09\/2017-un-bilan-en-demi-teinte\/","title":{"rendered":"2017 : Un bilan en demi-teinte"},"content":{"rendered":"<p><strong>Nous partageons l&rsquo;analyse faite ci-dessous par l&rsquo;Association Nationale des Gens du Voyage citoyens. En 2018, il nous faudra continuer \u00e0 agir pour faire peu \u00e0 peu tomber les obstacles \u00e0 l&rsquo;application de la l\u00e9gislation. L&rsquo;\u00e9galit\u00e9 des droits demeure pour l&rsquo;association Rencontres Tsiganes une priorit\u00e9.\u00a0<\/strong><\/p>\n<p><em>Bonjour,<\/em><\/p>\n<p><em>L\u2019ann\u00e9e 2017 s\u2019ach\u00e8ve dans quelques jours et nombre d\u2019entre vous tireront le bilan de leurs actions et\/ou du contexte dans lequel ils ont d\u00fb \u00e9voluer.<\/em><\/p>\n<p><em>Le fait marquant est, sans nul doute, l\u2019application de l\u2019abrogation des titres de circulation adopt\u00e9e fin janvier. Les r\u00e9calcitrants \u00e0 ce changement nous avaient agit\u00e9 le spectre de mille difficult\u00e9s. Or, \u00e0 l\u2019exception de celles rencontr\u00e9es en mati\u00e8re de domiciliation pour l\u2019enregistrement des entreprises, nous n\u2019avons pas eu de retours alarmistes sur d\u2019autres aspects. N\u00e9anmoins, nous estimons qu\u2019un nombre important de probl\u00e8mes rencontr\u00e9s rel\u00e8vent, le plus souvent peut-\u00eatre, d\u2019une r\u00e9elle insuffisance d\u2019explication et de p\u00e9dagogie sur le nouveau dispositif plut\u00f4t que de sa r\u00e9elle inadaptation. Certes, il reste \u00e0 am\u00e9liorer, mais il remet cependant au centre des priorit\u00e9s l\u2019acc\u00e8s aux droits des familles.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Tout n\u2019est pas acquis pour autant, loin s\u2019en faut. On l\u2019a notamment vu au cours de ce dernier trimestre avec les propositions de loi qui sont tomb\u00e9es, telles des m\u00e9t\u00e9orites, sur le bureau du S\u00e9nat et de l\u2019Assembl\u00e9e Nationale&#8230; Elles sont la marque de celles et ceux, encore trop nombreux, qui estiment que la sanction r\u00e9soudra tout et palliera leur incapacit\u00e9 \u00e0 innover et changer de regard.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Il reste d\u2019autres questions en suspens pour lesquelles l\u2019ANGVC a d\u00e9j\u00e0 pos\u00e9 des jalons, notamment en faisant adopter la cr\u00e9ation de nouveaux groupes de travail \u00e0 la Commission nationale, afin de faire entendre les revendications des Voyageurs.\u00a0Nous en d\u00e9nombrons quatre, parmi d\u2019autres, qui rev\u00eatent un caract\u00e8re d\u2019urgence essentiel\u00a0:<\/em><\/p>\n<p><em>&#8211;<\/em><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><em>la question de l\u2019urbanisme et de la reconnaissance de la r\u00e9sidence mobile comme logement, qui pose le droit d\u2019habiter quelque part en dehors d\u2019une aire d\u2019accueil et l\u2019acc\u00e8s aux droits sociaux aff\u00e9rents au logement<\/em><\/p>\n<p><em>&#8211;<\/em><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><em>la question de l\u2019acc\u00e8s au domaine public pour y d\u00e9velopper des activit\u00e9s \u00e9conomiques, qui est au c\u0153ur du mode de vie itin\u00e9rant<\/em><\/p>\n<p><em>&#8211;<\/em><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><em>la question de la scolarisation des enfants et de la formation des jeunes qui croise l\u2019\u00e9volution de notre soci\u00e9t\u00e9 avec une r\u00e9flexion \u00e0 porter sur la vie des g\u00e9n\u00e9rations futures de Voyageurs<\/em><\/p>\n<p><em>&#8211;<\/em><em>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/em><em>la question de l\u2019acc\u00e8s aux assurances qui cristallise la double d\u00e9finition de la r\u00e9sidence mobile comme v\u00e9hicule et, pour une cat\u00e9gorie de personnes dont c\u2019est l\u2019habitat permanent et principal, comme logement<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Je profite du parfum d\u2019humeur festive qui nous anime tous un peu ces jours-ci pour vous souhaiter de bonnes f\u00eates de No\u00ebl, \u00e0 vous d\u2019abord et \u00e0 vos proches. Je vous adresse \u00e9galement mes meilleurs v\u0153ux de sant\u00e9 et de succ\u00e8s dans toutes vos initiatives pour 2018 dont j\u2019esp\u00e8re qu\u2019elle sera nourrie de fructueux d\u00e9bats&#8230; afin que nos combats communs aboutissent.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><em>Cordialement,<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><strong><em>Association Nationale des Gens du Voyage Citoyens (ANGVC)<\/em><\/strong><\/p>\n<p><strong><em>Marc BEZIAT, le D\u00e9l\u00e9gu\u00e9 G\u00e9n\u00e9ral<\/em><\/strong><\/p>\n<p><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous partageons l&rsquo;analyse faite ci-dessous par l&rsquo;Association Nationale des Gens du Voyage citoyens. En 2018, il nous faudra continuer \u00e0 agir pour faire peu \u00e0 peu tomber les obstacles \u00e0 l&rsquo;application de la l\u00e9gislation. L&rsquo;\u00e9galit\u00e9 des droits demeure pour l&rsquo;association Rencontres Tsiganes une priorit\u00e9.\u00a0 Bonjour, L\u2019ann\u00e9e 2017 s\u2019ach\u00e8ve dans quelques jours et nombre d\u2019entre vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,17],"tags":[],"class_list":["post-13614","post","type-post","status-publish","format-standard","hentry","category-fabrique-du-droit","category-lois-decrets-et-circulaires"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=13614"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13614\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=13614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=13614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=13614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}