{"id":1349,"date":"2015-04-04T11:39:37","date_gmt":"2015-04-04T10:39:37","guid":{"rendered":"http:\/\/rt.boullier.fr\/?p=1349"},"modified":"2015-04-04T11:39:37","modified_gmt":"2015-04-04T10:39:37","slug":"art1349","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2015\/04\/04\/art1349\/","title":{"rendered":"Les Gens du voyage peuvent (doivent) voter !"},"content":{"rendered":"<p>C&rsquo;est une initiative collective \u00e0 saluer.<\/p>\n<p>Sur proposition de la FNASAT, l&rsquo;ANGVC a co-sign\u00e9 avec l&rsquo;ASNIT, France Libert\u00e9 Voyage et l&rsquo;UFAT \u00a0la reconduction d&rsquo;une campagne d&rsquo;incitation et d&rsquo;information initi\u00e9e en 2011 sur l&rsquo;inscription sur les listes \u00e9lectorales pour les Voyageurs.<\/p>\n<p>Cette version 2015, qui int\u00e8gre les modifications apport\u00e9es par la d\u00e9cision du Conseil constitutionnel le 5 octobre 2012, nous vous invitons \u00e0 la diffuser sans aucune mod\u00e9ration dans\u00a0vos r\u00e9seaux et \u00e0 la faire connaitre autour de vous avec pour perspective imm\u00e9diate les prochaines \u00e9lections r\u00e9gionales du mois de d\u00e9cembre prochain.<\/p>\n<p>En vous remerciant de votre contribution \u00e0 cette initiative citoyenne.<\/p>\n<p><a href=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/2015\/04\/Inscription_sur_les_listes_2015.pdf\">Inscription sur les listes \u00e9lectorales<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plusieurs  associations se sont regroup\u00e9es  pour une campagne d&rsquo; inscription sur les listes \u00e9lectorales.  Un geste de reconnaissance citoyenne plus que jamais n\u00e9cessaire. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,11],"tags":[68],"class_list":["post-1349","post","type-post","status-publish","format-standard","hentry","category-fabrique-du-droit","category-gens-du-voyage","tag-gens-du-voyage"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=1349"}],"version-history":[{"count":1,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1349\/revisions"}],"predecessor-version":[{"id":14192,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1349\/revisions\/14192"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=1349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=1349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=1349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}