{"id":13316,"date":"2017-07-09T08:48:43","date_gmt":"2017-07-09T06:48:43","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=13316"},"modified":"2017-07-09T08:48:43","modified_gmt":"2017-07-09T06:48:43","slug":"le-prefet-fait-etat-de-son-impuissance","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2017\/07\/09\/le-prefet-fait-etat-de-son-impuissance\/","title":{"rendered":"Le pr\u00e9fet fait \u00e9tat de son impuissance."},"content":{"rendered":"<p><strong>\u00a0<\/strong><\/p>\n<p>C\u2019est devant une vingtaine de fonctionnaires de l\u2019Etat, une \u00e9lue du conseil d\u00e9partemental et six repr\u00e9sentants d\u2019associations de voyageurs que s\u2019est tenue le 28 juin 2017 la derni\u00e8re r\u00e9union de la commission d\u00e9partementale des gens du voyage des Bouches du Rh\u00f4ne. On a, une fois de plus, not\u00e9 l&rsquo;absence des nombreux maires pourtant membres\u00a0 de cette commission.<\/p>\n<p>&nbsp;<\/p>\n<p>La pr\u00e9sentation des articles de la loi \u201c\u00e9galit\u00e9 et citoyennet\u00e9\u201c et les d\u00e9crets d\u2019application les plus r\u00e9cents ont fait l\u2019objet d\u2019une longue pr\u00e9sentation par le service. En cons\u00e9quence la composition de la commission va \u00eatre revue et le sch\u00e9ma d\u00e9partemental d\u2019accueil sera une nouvelle fois remis \u00e0 plat. Le nouveau sch\u00e9ma est pr\u00e9vu pour \u00eatre op\u00e9rationnel au printemps 2019\u00a0!!!<\/p>\n<p>&nbsp;<\/p>\n<p>On notera que le sch\u00e9ma d\u2019origine a \u00e9t\u00e9 modifi\u00e9 \u00e0 de nombreuse reprises et qu\u2019\u00e0 ce jour, moins d\u2019un quart des places pr\u00e9vues \u00e0 l\u2019origine est aujourd\u2019hui ouvertes. Les maires de communes r\u00e9calcitrantes peuvent se rassurer et continuer \u00e0 d\u00e9fier la loi et poursuivre les gens du voyage de leur vindicte.<\/p>\n<p>&nbsp;<\/p>\n<p>Les repr\u00e9sentants associatifs ont alors, tour \u00e0 tour, fait part de leurs d\u00e9sillusions et les multiples obstacles rencontr\u00e9s dans le d\u00e9partement pour faire respecter la loi. Ils estiment que, si le repr\u00e9sentant de l\u2019Etat dans le d\u00e9partement ne met pas en \u0153uvre les moyens dont il dispose pour faire respecter la loi, les nouvelles mesures l\u00e9gislatives et r\u00e9glementaires pr\u00e9sent\u00e9es n\u2019auront aucun effet. La r\u00e9alisation d\u2019une nouvelle \u00e9tude des besoins est inutile et co\u00fbteuse de m\u00eame qu\u2019un nouveau sch\u00e9ma s\u2019il n\u2019est pas appliqu\u00e9.<\/p>\n<p>Malgr\u00e9 la pr\u00e9sentation de cas flagrants de discrimination des droits des gens du voyage le pr\u00e9fet n\u2019a pu apporter, une fois de plus aucune r\u00e9ponse concr\u00e8te.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Pour ma part, j\u2019ai exprim\u00e9 devant la commission, le point de l\u2019association Rencontres Tsiganes dont on lira le texte ci-dessous.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Monsieur le Pr\u00e9fet, mesdames et messieurs<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Mandat\u00e9 par l\u2019association Rencontres Tsiganes en Provence-Alpes-C\u00f4te-d\u2019Azur j\u2019ai pris part depuis l\u2019origine, <strong>le 7 novembre 2001,<\/strong> \u00e0 toutes les r\u00e9unions de cette commission et j\u2019en d\u00e9tiens tous les proc\u00e8s-verbaux. J\u2019ai, \u00e0 de nombreuses occasions et dans d\u2019autres c\u00e9nacles, tent\u00e9 de faire entendre la voix des gens du voyage. Ceci me permet, vous le comprendrez, de dresser devant vous et les institutions que vous repr\u00e9sentez, un bilan de ces 16 ann\u00e9es d\u2019activit\u00e9s.\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Concernant l\u2019acc\u00e8s aux droits des gens du voyage, si, \u00e0 l\u2019\u00e9chelle nationale, nous avons pu constater de r\u00e9elles avanc\u00e9es qui conduisent \u00e0 la reconnaissance de la citoyennet\u00e9 pleine et enti\u00e8re des gens du voyage et aux \u00e9volutions l\u00e9gislatives et r\u00e9glementaires qui font l\u2019objets de l\u2019ordre du jour de cette r\u00e9union, <strong>force est de constater que, dans le d\u00e9partement de Bouches -du-Rh\u00f4ne, les droits des gens du voyage et leurs conditions de vie se sont\u00a0 s\u00e9rieusement d\u00e9grad\u00e9es durant les derni\u00e8res ann\u00e9es.<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Sans revenir sur les multiples rapports, interventions et d\u00e9marches que nous avons entrepris pour que, au minimum, la l\u00e9gislation soit respect\u00e9e dans ce d\u00e9partement, Je me contenterai, aujourd\u2019hui, d\u2019attirer votre attention \u00e0 titre d\u2019exemple sur trois les trois dossiers suivants\u00a0:<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><u>\u00a01\u00b0L\u2019aire d\u2019accueil de Saint Menet \u00e0 Marseille<\/u>\u00a0<\/em><\/p>\n<p><em>Cette aire d\u2019accueil controvers\u00e9e a \u00e9t\u00e9 ferm\u00e9e pour travaux urgents en f\u00e9vrier dernier, n\u2019est toujours pas r\u00e9-ouverte et les travaux ne sont pas achev\u00e9s. A ce jour il n\u2019y a pas d\u2019aire d\u2019accueil \u00e0 Marseille alors que le sch\u00e9ma en pr\u00e9voyait deux \u00e0 l\u2019origine. O\u00f9 vont les voyageurs ? Pour la plus grande, partie ils stationnent de mani\u00e8re irr\u00e9guli\u00e8re un peu partout en fonction de la proximit\u00e9 des \u00e9coles et de leurs activit\u00e9s. Des familles s\u00e9journant, faute de mieux, sur un terrain priv\u00e9 \u00e0 la Penne-sur-Huveaune sont convoqu\u00e9es au TGI de Marseille en r\u00e9f\u00e9r\u00e9 le 5 juillet prochain. <strong>Qui est responsable ? va d\u00e9fendre leurs droits\u00a0?\u00a0 <\/strong><\/em><\/p>\n<p><em><strong>\u00a0<\/strong><\/em><\/p>\n<p><em><u>2\u00b0Terrain de l\u2019Anjoly \u00e0 Vitrolles.\u00a0<\/u><\/em><\/p>\n<p><em>Apr\u00e8s de multiples incidents plus ou moins graves depuis un an, aucune perspective s\u00e9rieuse n\u2019\u2019est propos\u00e9e \u00e0 ce jour \u00e0 la trentaine de familles install\u00e9es depuis parfois plus de dix ans sur ce terrain appartenant \u00e0 la commune. Le risque d\u2019incidents et de conflits plus ou moins violents s\u2019accroit de jour en jour.\u00a0 Un article de de presse relatant la propret\u00e9 des rues \u00e0 Marseille a mis en avant une photo prise \u00e0 Vitrolles le 27 f\u00e9vrier \u00e0 proximit\u00e9 du terrain des voyageurs, sans mentionner que le stock de d\u00e9chets \u00e9tait d\u00fb au refus de l\u2019entreprise de nettoiement d\u2019intervenir sur le site.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em><u>Chemin des Vaneu \u00e0 Cabri\u00e8s Calas<\/u><\/em><\/p>\n<p><em>Une vingtaine de familles sont install\u00e9es parfois depuis plusieurs ann\u00e9es sur des parcelles dont elles sont propri\u00e9taires. La plupart d\u2019entre-elles disposent de branchements \u00e9lectriques d\u00e9finitifs de la part d\u2019ENEDIS. Cinq familles ont re\u00e7u un courrier d\u2019ENEDIS leur annon\u00e7ant que leur contrat prendrait fin dans les prochains jours. \u00a0Rappelons qu\u2019une telle d\u00e9cision est ill\u00e9gale et qu\u2019elle a fait l\u2019objet depuis de nombreuses ann\u00e9es de d\u00e9cisions judiciaires condamnant ENEDIS \u00e0 maintenir la fourniture de courant.\u00a0Nous souhaitons tr\u00e8s vivement avoir une r\u00e9ponse au courrier concernant cette question envoy\u00e9e \u00e0 Monsieur le Pr\u00e9fet en date du 12 janvier dernier et rest\u00e9e \u00e0 ce jour sans r\u00e9ponse.\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Je conclurai cette derni\u00e8re intervention en souhaitant vivement que ceux qui auront la charge, dans une commission d\u00e9partementale \u00e9largie avec de nouvelles comp\u00e9tences et de nouveaux moyens, prennent la mesure du chemin qui reste \u00e0 accomplir pour, que dans ce d\u00e9partement, les discriminations et les refus de droits dont sont victimes une partie de nos concitoyens soient enfin abolis.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Marseille le 28 juin 2017<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Alain FOUREST\u00a0<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 C\u2019est devant une vingtaine de fonctionnaires de l\u2019Etat, une \u00e9lue du conseil d\u00e9partemental et six repr\u00e9sentants d\u2019associations de voyageurs que s\u2019est tenue le 28 juin 2017 la derni\u00e8re r\u00e9union de la commission d\u00e9partementale des gens du voyage des Bouches du Rh\u00f4ne. On a, une fois de plus, not\u00e9 l&rsquo;absence des nombreux maires pourtant membres\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,16,17],"tags":[],"class_list":["post-13316","post","type-post","status-publish","format-standard","hentry","category-editos","category-rub82","category-lois-decrets-et-circulaires"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=13316"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/13316\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=13316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=13316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=13316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}