{"id":1325,"date":"2015-01-09T15:50:02","date_gmt":"2015-01-09T14:50:02","guid":{"rendered":"http:\/\/rt.boullier.fr\/?p=1325"},"modified":"2015-01-09T15:50:02","modified_gmt":"2015-01-09T14:50:02","slug":"art1325","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2015\/01\/09\/art1325\/","title":{"rendered":"L\u2019anti-tsiganisme en France : un inqui\u00e9tant sympt\u00f4me"},"content":{"rendered":"<p style=\"text-align: justify;\">Voil\u00e0 12 ans qu&rsquo;avec obstination nous tentons d&rsquo;alerter nos concitoyens sur un inqui\u00e9tant ph\u00e9nom\u00e8ne qui se diffuse dans l&rsquo;opinion bien au-del\u00e0 du cercle heureusement encore restreint des racistes av\u00e9r\u00e9s. En septembre 2006 nous avons organis\u00e9 au si\u00e8ge du Conseil r\u00e9gional de Provence-Alpes-C\u00f4te-d&rsquo;Azur un colloque pour pr\u00e9senter le rapport r\u00e9alis\u00e9 en 2005 par Lanna HOLLO \u00e0 la demande du Centre Europ\u00e9en pour les Droits des Roms (<a href=\"http:\/\/www.errc.org\/\" target=\"_blank\" rel=\"noopener\">ERRC<\/a>). Ce rapport exhaustif (disponible au Centre de Ressources de Rencontres Tsiganes) portait sur le traitement des tsiganes, voyageurs et roms migrants en France, du point de vue des droits de l&rsquo;Homme. \u00ab\u00a0La majeure partie du territoire fran\u00e7ais semble inaccessible aux tsiganes et aux voyageurs, \u00e0 l&rsquo;exception de certaines zones insalubres, pollu\u00e9es et ghetto\u00efs\u00e9es, bien \u00e0 l&rsquo;abri du regard des autres r\u00e9sidents. De m\u00eame, les quelques milliers de roms migrants se trouvant sur le territoire fran\u00e7ais sont soumis \u00e0 des politiques inhumaines et Kafka\u00efennes dans le simple but de les inciter \u00e0 quitter la France. Ils vivent dans des conditions sordides et ind\u00e9centes et se voient r\u00e9guli\u00e8rement expuls\u00e9s de leurs pr\u00e9caires camps et squats, d\u00e9plac\u00e9s vers la municipalit\u00e9 voisine\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ce rapport r\u00e9alis\u00e9 il y a 10 ans n&rsquo;a pas eu h\u00e9las un grand succ\u00e8s de librairie et sa relecture montre que les conditions scandaleuses de s\u00e9jour et d&rsquo;accueil faites aux Roms et aux Tsiganes ont perdur\u00e9 et se sont souvent aggrav\u00e9es. Plus inqui\u00e9tant encore, la relative banalisation des comportements et des propos ouvertement racistes ne semble pas \u00e9mouvoir beaucoup de ceux qui se revendiquent respectueux des Droits de l&rsquo;Homme. Face une telle d\u00e9rive et devant l&rsquo;inefficacit\u00e9 de nos alertes, il nous faut tenter de comprendre les raisons d&rsquo;un tel \u00e9chec.<\/p>\n<p style=\"text-align: justify;\">Comme le soulignent \u00e0 juste titre plusieurs chercheurs, la stigmatisation des responsables politiques, des \u00e9lus, des m\u00e9dias et finalement d&rsquo;une grande partie de l&rsquo;opinion sur &lsquo;la question Roms&rsquo;\u00a0serait un leurre. La d\u00e9marche adopt\u00e9e consiste \u00e0 faire porter \u00e0 autrui la responsabilit\u00e9 des errements auxquels nous sommes confront\u00e9s. Cinq sujets d&rsquo;actualit\u00e9 dominent nos d\u00e9bats\u00a0: le ch\u00f4mage, les sans abris, la pauvret\u00e9, la d\u00e9centralisation, l&rsquo;Europe. Imaginons que sur chacun de ces sujets des politiques ambitieuses et efficaces soient mises en oeuvre pour y r\u00e9pondre. Alors, l&rsquo;acc\u00e8s \u00e0 un emploi, \u00e0 un minimum de ressources et \u00e0 un habitat d\u00e9cent auraient permis en r\u00e9pondant aux attentes de nos concitoyens le plus fragiles de faire aussi face aux besoins de quelques centaines de familles migrantes chass\u00e9es de chez elles par la mis\u00e8re et la x\u00e9nophobie. Mais comme nous le r\u00e9p\u00e8te r\u00e9guli\u00e8rement le Pr\u00e9fet, comment proposer un logement \u00e0 une famille de Roms alors que les listes d&rsquo;attente ne cessent de cro\u00eetre\u00a0? Les derniers arriv\u00e9s ferment la porte.<\/p>\n<p style=\"text-align: justify;\">De m\u00eame, si les gouvernements successifs n&rsquo;avaient pas laiss\u00e9 aux seuls \u00e9lus locaux la responsabilit\u00e9 de l&rsquo;accueil des Roms et des Tsiganes et si la l&rsquo;Union Europ\u00e9enne avait fait preuve de plus de perspicacit\u00e9 lors de l&rsquo;entr\u00e9e de ces nouveaux pays, il n&rsquo;y aurait pas de probl\u00e8me Rom. Si la l\u00e9gislation discriminatoire et anticonstitutionnelle appliqu\u00e9e aux gens du voyage \u00e9tait enfin supprim\u00e9e\u00a0et si leur mode d&rsquo;habitat \u00e9tait reconnu, si le respect des droits pour tous, si, etc&#8230;<\/p>\n<p style=\"text-align: justify;\">La politique du bouc \u00e9missaire sert ainsi facilement d&rsquo;alibi et nous emp\u00eache d&rsquo;affronter les\u00a0questions sur l&rsquo;avenir de notre soci\u00e9t\u00e9 et sur notre capacit\u00e9 \u00e0 vivre ensemble. A l&rsquo;aube d&rsquo;une nouvelle ann\u00e9e, souhaitons que responsables et citoyens \u00e9clair\u00e9s, chacun accepte de renoncer aux solutions de facilit\u00e9 consistant \u00e0 rejeter sur d&rsquo;autres nos erreurs d&rsquo;analyse et de comportement.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Marseille le\u00a06 janvier 2015<br \/>\nAlain FOUREST<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voil\u00e0 12 ans qu&rsquo;avec obstination nous tentons d&rsquo;alerter nos concitoyens sur un inqui\u00e9tant ph\u00e9nom\u00e8ne qui se diffuse dans l&rsquo;opinion bien au-del\u00e0 du cercle heureusement encore restreint des racistes av\u00e9r\u00e9s. En septembre 2006 nous avons organis\u00e9 au si\u00e8ge du Conseil r\u00e9gional de Provence-Alpes-C\u00f4te-d&rsquo;Azur un colloque pour pr\u00e9senter le rapport r\u00e9alis\u00e9 en 2005 par Lanna HOLLO \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,16],"tags":[],"class_list":["post-1325","post","type-post","status-publish","format-standard","hentry","category-editos","category-rub82"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}