{"id":1297,"date":"2014-10-11T11:57:15","date_gmt":"2014-10-11T10:57:15","guid":{"rendered":"http:\/\/rt.boullier.fr\/?p=1297"},"modified":"2014-10-11T11:57:15","modified_gmt":"2014-10-11T10:57:15","slug":"art1297","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2014\/10\/11\/art1297\/","title":{"rendered":"Un nouveau patron \u00e0 la DIHAL"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>\u00ab\u00a0A l&rsquo;heure o\u00f9 je quitte mes fonctions de D\u00e9l\u00e9gu\u00e9 interminist\u00e9riel pour l&rsquo;h\u00e9bergement et l&rsquo;acc\u00e8s au logement des personnes sans abri ou mal log\u00e9es, je souhaite remercier toutes celles et ceux qui accompagnent l&rsquo;aventure de la Dihal.<br \/>\nTout au long de ces six ann\u00e9es, avec mon \u00e9quipe, nous avons essay\u00e9 de transformer la prise en charge des personnes les plus exclues. Je suis fier du travail accompli et je mesure tout ce qu&rsquo;il reste \u00e0 faire.<br \/>\nLa pr\u00e9carit\u00e9 continue de progresser dans le pays, plus que jamais il est n\u00e9cessaire de mener le combat pour la faire reculer.<br \/>\nJ&rsquo;ai toujours consid\u00e9r\u00e9 que servir l&rsquo;Etat, c&rsquo;est s&rsquo;engager au service de laj ustice, des plus d\u00e9favoris\u00e9s et de l&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral. Dans cette p\u00e9riode de profondes mutations \u00e9conomiques et sociales, notre pays a besoin de fonctionnaires et de citoyens qui portent avec conviction cet id\u00e9al et cette exigence.<br \/>\nJe souhaite un plein succ\u00e8s \u00e0 mon successeur Sylvain Mathieu.<br \/>\nA bient\u00f4t.\u00a0\u00bb<br \/>\n&#8211; Alain R\u00e9gnier &#8211;<\/em><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span data-scayt_word=\"R\u00e9gnier\" data-scaytid=\"7\">Sylvain Mathieu, un \u00e9narque sp\u00e9cialiste de l&rsquo;action sociale, a \u00e9t\u00e9 nomm\u00e9 mercredi 8 octobre par d\u00e9cret \u00e0 la t\u00eate de la d\u00e9l\u00e9gation interminist\u00e9rielle pour l&rsquo;h\u00e9bergement et l&rsquo;acc\u00e8s au logement des personnes sans-abri ou mal-log\u00e9s (DIHAL), dont les missions incluent des probl\u00e9matiques concernant les Roms et les \u00ab\u00a0gens du voyage\u00a0\u00bb, a annonc\u00e9 le minist\u00e8re du Logement&#8230;.<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sylvain MATHIEU remplace Alain REGNIER \u00e0 a DIHAL  <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,18],"tags":[43,50],"class_list":["post-1297","post","type-post","status-publish","format-standard","hentry","category-habitat-subi","category-migrants-roms","tag-bidonvilles","tag-dihal"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=1297"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1297\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=1297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}