{"id":12786,"date":"2016-06-28T16:54:12","date_gmt":"2016-06-28T14:54:12","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=12786"},"modified":"2016-06-28T16:54:12","modified_gmt":"2016-06-28T14:54:12","slug":"sur-laire-de-saint-menet-un-air-dopera","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2016\/06\/28\/sur-laire-de-saint-menet-un-air-dopera\/","title":{"rendered":"Sur l&rsquo;aire de Saint Menet : un air d&rsquo;op\u00e9ra."},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12788\" src=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/Ope\u0301ra-a\u0300-saint-Menet--300x169.jpg\" alt=\"Ope\u0301&amp;ra a\u0300 saint Menet\" width=\"300\" height=\"169\" \/><\/p>\n<p style=\"text-align: justify;\">Samedi 11 juin au soir, une surprise attendait les voyageurs install\u00e9s sur l&rsquo;aire de Saint-Menet \u00e0 Marseille. L&rsquo;arriv\u00e9e de\u00a0 quelques personnes portant de dr\u00f4les\u00a0 de cartables\u00a0 a intrigu\u00e9 les nombreux enfants pr\u00e9sents sur le site . Puis des chaises et des bancs ont \u00e9t\u00e9 install\u00e9s entre les caravanes.\u00a0 L&rsquo;attente \u00e9tait longue et les questions nombreuses.\u00a0 Puis les nouveaux arrivants s&rsquo;installent et sortent de dr\u00f4les d&rsquo;instruments de musiques de leurs \u00e9tuis. Au d\u00e9but c&rsquo;est curieux ils soufflent chacun \u00e0 leur tour puis tous ensemble dans leurs\u00a0 instruments. Chut ! il faut faire silence . C&rsquo;est Pierre qui commence\u00a0 puis, peu \u00e0 peu, tous les animaux\u00a0 se font entendre.\u00a0 Pierre arrive enfin a attraper le loup . On a eu peur. Heureusement il avait une grande pa\u00eblla qui nous attendait.<\/p>\n<p style=\"text-align: justify;\">\u00a0Bravo les artistes !!!!<\/p>\n<p style=\"text-align: justify;\"><em>A propos<\/em><br \/>\n<em> L\u2019aire d\u2019accueil des gens du voyage de Saint-Menet \u00e0 Marseille est l\u2019une des rares \u00e0 b\u00e9n\u00e9ficier d\u2019un centre social permanent, lieu d\u2019\u00e9change et de vie o\u00f9 tsiganes, rroms et gadj\u00e9 se c\u00f4toient.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Air(e) d&rsquo;Op\u00e9ra est \u00e0 la fois une soir\u00e9e musicale organis\u00e9e sur une aire d&rsquo;accueil et un programme qui participe \u00e0 l&rsquo;ouverture du champ culturel et artistique en cr\u00e9ant<\/em><br \/>\n<em> du lien social.<\/em><br \/>\n<em> Les musiciens issus d&rsquo;une formation de l&rsquo;Orchestre Philharmonique de Marseille, le service d&rsquo;animation du centre social de l&rsquo;aire d&rsquo;accueil des gens du voyage de St Menet, la m\u00e9diath\u00e8que de la Penne sur Huveaune et le P\u00f4le d&rsquo;Information Carr\u00e9 Culture, accompagnent les familles de l&rsquo;aire d&rsquo;accueil et le public sur des temps d&rsquo;\u00e9change, de partage et d&rsquo;ouverture en vue du rassemblement<\/em><br \/>\n<em> Air(e) d&rsquo;Op\u00e9ra qui cette ann\u00e9e donnera lieu \u00e0 un concert-lecture autour du conte musical Pierre et le Loup de S. Prokofief<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Samedi 11 juin au soir, une surprise attendait les voyageurs install\u00e9s sur l&rsquo;aire de Saint-Menet \u00e0 Marseille. L&rsquo;arriv\u00e9e de\u00a0 quelques personnes portant de dr\u00f4les\u00a0 de cartables\u00a0 a intrigu\u00e9 les nombreux enfants pr\u00e9sents sur le site . Puis des chaises et des bancs ont \u00e9t\u00e9 install\u00e9s entre les caravanes.\u00a0 L&rsquo;attente \u00e9tait longue et les questions nombreuses.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12788,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,25],"tags":[],"class_list":["post-12786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-musique-et-cinema","category-sur-le-terrain"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=12786"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=12786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=12786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=12786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}