{"id":12646,"date":"2016-05-20T19:07:04","date_gmt":"2016-05-20T17:07:04","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=12646"},"modified":"2016-05-20T19:07:04","modified_gmt":"2016-05-20T17:07:04","slug":"tous-en-fete-avec-les-roms","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2016\/05\/20\/tous-en-fete-avec-les-roms\/","title":{"rendered":"Tous en f\u00eate avec les Roms"},"content":{"rendered":"<p><strong><a href=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/AfficheA4.pdf\">AfficheA4<\/a><\/strong><\/p>\n<p><strong>RAPPEL<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Les collectifs de soutien aux Roms des Bouches du Rh\u00f4ne vous convient \u00e0 une manifestation intitul\u00e9e \u00ab\u00a0Tous en f\u00eate avec les Roms\u00a0\u00bb l<strong>e samedi 11 juin 2016, de 14h \u00e0 minuit, \u00e0 la Maison du Peuple de Gardanne.<\/strong><br \/>\nLe programme et l&rsquo;affiche de la manifestation sont en pi\u00e8ces jointes.<a href=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/Programme-de\u0301finitif-3.pdf\">Programme de\u0301finitif\u00a0<\/a><\/p>\n<p>Apr\u00e8s de longues ann\u00e9es pass\u00e9es par d&rsquo;innombrables b\u00e9n\u00e9voles du d\u00e9partement et d&rsquo;ailleurs \u00e0 accompagner les familles Roms en d\u00e9sh\u00e9rence pour tenter de leur permettre d&rsquo;acc\u00e9der \u00e0 des conditions de vie dignes et d\u00e9centes, les collectifs 13 veulent faire de cette manifestation un temps fort de d\u00e9bats, rencontres, information, mais aussi de f\u00eate (voir programme) !<\/p>\n<p>Merci de le faire savoir dans tous vos r\u00e9seaux associatifs et amicaux, et de venir vous-m\u00eames le 11 juin avec enfants, petits-enfants, copains&#8230; !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AfficheA4 RAPPEL &nbsp; Les collectifs de soutien aux Roms des Bouches du Rh\u00f4ne vous convient \u00e0 une manifestation intitul\u00e9e \u00ab\u00a0Tous en f\u00eate avec les Roms\u00a0\u00bb le samedi 11 juin 2016, de 14h \u00e0 minuit, \u00e0 la Maison du Peuple de Gardanne. Le programme et l&rsquo;affiche de la manifestation sont en pi\u00e8ces jointes.Programme de\u0301finitif\u00a0 Apr\u00e8s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,25],"tags":[],"class_list":["post-12646","post","type-post","status-publish","format-standard","hentry","category-non-classe","category-sur-le-terrain"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=12646"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12646\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=12646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=12646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=12646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}