{"id":12537,"date":"2016-03-21T18:15:08","date_gmt":"2016-03-21T17:15:08","guid":{"rendered":"https:\/\/archives.rencontrestsiganes.org\/?p=12537"},"modified":"2016-03-21T18:15:08","modified_gmt":"2016-03-21T17:15:08","slug":"une-reconnaissance-trop-longtemps-attendue","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2016\/03\/21\/une-reconnaissance-trop-longtemps-attendue\/","title":{"rendered":"Une reconnaissance trop longtemps attendue"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #993300;\">Depuis de nombreuses ann\u00e9es, les d\u00e9marches des associations de voyageurs se multiplient afin que la France reconnaisse sa participation au g\u00e9nocide des Tsiganes durant la derni\u00e8re guerre mondiale. Si, \u00e0 ce jour, les diverses propositions de loi parlementaires n\u2019ont pu aboutir, il semble que, depuis quelque temps, le gouvernement ouvre la voie \u00e0 cette reconnaissance. La pr\u00e9sence de Jean marc Todeschini, Secr\u00e9taire d\u2019Etat aupr\u00e8s du Ministre de la D\u00e9fense, le 15 d\u00e9cembre dernier \u00e0 la c\u00e9r\u00e9monie lors du 70\u00e8me anniversaire de la lib\u00e9ration du camp de Jargeau est un signe positif. Il en est de m\u00eame de l\u2019inauguration en octobre dernier par Manuel VALLS du m\u00e9morial du camp de Rivesaltes dans lequel des milliers d\u2018Espagnols fuyant Franco, des Juifs et des Tsiganes ont \u00e9t\u00e9 enferm\u00e9s par Vichy. Dans notre r\u00e9gion, comme chaque ann\u00e9e au moment du p\u00e8lerinage des Saintes Maries de la Mer, \u00e0 l\u2019initiative de l\u2019Association des Fils et Filles d\u2019Intern\u00e9s du camp de Saliers, une c\u00e9r\u00e9monie rassemble les familles de voyageurs et les autorit\u00e9s autour du monument \u00e9rig\u00e9 sur place. Dans les prochains mois, d\u2019autres manifestations du m\u00eame type vont avoir lieu et pourraient se conclure avant la fin de l\u2019ann\u00e9e par une manifestation nationale de reconnaissance. Esp\u00e9rons que ces d\u00e9clarations permettront enfin aux quelques tsiganes encore parmi nous et qui ont subi ces atrocit\u00e9s ainsi qu\u2019\u00e0 leurs descendants de retrouver leur dignit\u00e9 de citoyens.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300;\"><a href=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/Jargeau-ce\u0301re\u0301monie-15-de\u0301cembre-2015-1.pdf\" rel=\"\">Jargeau, ce\u0301re\u0301monie, 15 de\u0301cembre 2015<\/a><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12555\" src=\"https:\/\/archives.rencontrestsiganes.org\/wp-content\/uploads\/me\u0301morial-tsiganes-Berlin-1-300x169.jpg\" alt=\"me\u0301morial tsiganes Berlin\" width=\"300\" height=\"169\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300;\">Cette p\u00e9riode noire de notre histoire a resurgi r\u00e9cemment en Allemagne lors d\u2019un colloque \u00e0 l\u2019initiative du Conseil Central des Roms et de la Cour de Cassation Allemande. Il a \u00e9t\u00e9 rappel\u00e9 une d\u00e9cision de la plus haute instance judiciaire allemande concernant l\u2019indemnisation des Tsiganes prise en ces termes en 1956\u00a0 <em>\u00ab\u00a0ces populations\u00a0sont d\u2019exp\u00e9rience enclines \u00e0 la d\u00e9linquance, en particulier au vol et \u00e0 l\u2019escroquerie\u00a0; elles sont d\u00e9pourvues en maintes mani\u00e8res des incitations morales au respect de la propri\u00e9t\u00e9 d\u2019autrui car, \u00e0 l\u2019\u00e9gal des peuples primitifs, un instinct d\u00e9brid\u00e9 d\u2019appropriation les d\u00e9finit\u00a0\u00bb.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300;\">R\u00e9paration vient d\u2019\u00eatre faite de cette caract\u00e9risation d\u00e9gradante et diffamante. \u00ab\u00a0<em>La pr\u00e9sidente de la BGH, Bettina Limperg, a affirm\u00e9 au cours du colloque de Karlsruhe, que \u00ab\u00a0cette jurisprudence (de 1956) nous couvre de honte\u00a0\u00bb et que la Cour s\u2019en distancie d\u00e9finitivement.\u00a0\u00bb<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300;\">Cette r\u00e9paration tardive doit \u00eatre largement diffus\u00e9e car, comme le souligne Eric Fassin, une telle stigmatisation est encore pr\u00e9sente aujourd\u2019hui dans les mentalit\u00e9s de nombres de nos concitoyens y compris les plus responsables. Ainsi Manuel VALLS, alors Ministre de l\u2019Int\u00e9rieur estimait en 2013 \u00e0 propos des Roms\u00a0: \u00ab\u00a0<em>les occupants de campements ne souhaitent pas s\u2019int\u00e9grer dans notre pays pour des raisons culturelles ou parce qu\u2019ils sont entre les mains de r\u00e9seaux vers\u00e9s dans la mendicit\u00e9 ou la prostitution\u00a0\u00bb et que ces gens \u00ab\u00a0ont des modes de vie extr\u00eamement diff\u00e9rents des n\u00f4tres et qui sont \u00e9videmment en confrontation\u00a0\u00bb.\u00a0<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300;\">Ce rappel m\u00e9moriel, parfois d\u00e9cri\u00e9, a le m\u00e9rite de mettre en lumi\u00e8re des errements du pass\u00e9 qui ne s\u2019effacent pas et qui, \u00e0 chaque instant peuvent resurgir des paroles et des actes indignes de notre civilisation. Il faut esp\u00e9rer qu\u2019en France la reconnaissance attendue envers les Tsiganes soit \u00e0 la hauteur des celle des juges Allemands.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #993300;\">Marseille le 20 mars 2016<\/span><\/p>\n<p><span style=\"color: #993300;\">Alain FOUREST<\/span><\/p>\n<p><span style=\"color: #993300;\"><strong>\u00a0<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis de nombreuses ann\u00e9es, les d\u00e9marches des associations de voyageurs se multiplient afin que la France reconnaisse sa participation au g\u00e9nocide des Tsiganes durant la derni\u00e8re guerre mondiale. Si, \u00e0 ce jour, les diverses propositions de loi parlementaires n\u2019ont pu aboutir, il semble que, depuis quelque temps, le gouvernement ouvre la voie \u00e0 cette reconnaissance. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,16],"tags":[],"class_list":["post-12537","post","type-post","status-publish","format-standard","hentry","category-editos","category-rub82"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=12537"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/12537\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=12537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=12537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=12537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}