{"id":1145,"date":"2013-05-05T11:44:06","date_gmt":"2013-05-05T10:44:06","guid":{"rendered":"http:\/\/rt.boullier.fr\/?p=1145"},"modified":"2013-05-05T11:44:06","modified_gmt":"2013-05-05T10:44:06","slug":"art1145","status":"publish","type":"post","link":"https:\/\/archives.rencontrestsiganes.org\/index.php\/2013\/05\/05\/art1145\/","title":{"rendered":"Un voisinage qui risque de mal tourner, \u00e0 moins que ?"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Marine Le Pen pr\u00e8s d&rsquo;un camp rom&nbsp;: <br \/><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>o\u00f9 sont les autres politiques&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\"><\/p>\n<p style=\"text-align: justify;\"><em>Marine Le Pen dans un bidonville&nbsp;! La nouvelle est arriv\u00e9e aussi incongrue par son intitul\u00e9 que rapide par son contenu.<br \/>Marine Le Pen \u00e9tait le 25 avril, au bidonville de Wissous, dans l&rsquo;Essonne. Ce bidonville, nous le connaissons bien, il est le r\u00e9sultat de deux pr\u00e9c\u00e9dentes expulsions en 2012. <\/em><\/p>\n<p style=\"text-align: justify;\">Cette&nbsp;scandaleuse conf\u00e9rence de presse de Marine LE PEN \u00e0 proximit\u00e9 d&rsquo;un camp de Roms&nbsp;est un signal inqui\u00e9tant.&nbsp;Une telle manipulation de l&rsquo;opinion&nbsp;risque de se multiplier \u00e0 l&rsquo;approche des \u00e9lections municipales et ne sera pas exclusivement le fait des candidats du FN . On conna\u00eet d\u00e9ja dans la r\u00e9gion de nombreux \u00e9lus ou candidats de droite comme de gauche qui sont&nbsp;pr\u00eats a enfourcher cette odieuse m\u00e9thode du bouc \u00e9missaire.&nbsp;<\/p>\n<div style=\"text-align: center\"><a href='https:\/\/archives.rencontrestsiganes.org\/IMG\/jpg\/les_roms_en_errance_a_Marseille.jpg' type=\"image\/jpeg\" title=\"JPEG - 47.7 ko\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/archives.rencontrestsiganes.org\/local\/cache-vignettes\/L110xH63\/les_roms_en_errance_a_Marseille-d39cf.jpg?date=1367744485\" alt=\"\" class=\"miniature_document\" height=\"74\" width=\"138\"><\/a><\/div>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Dans les Bouches-du-Rh\u00f4ne, on lira ci-joint&nbsp;le dernier communiqu\u00e9 du comit\u00e9&nbsp; 13 de soutien aux Roms&nbsp; sur ce sujet. Et pourtant une municipalit\u00e9, celle de GARDANNE, a eu le courage de faire face aux multiples pressions&nbsp;et de fournir \u00e0 quelques familles des conditions de vie acceptables. Les propos du Pr\u00e9fet de R\u00e9gion, en visite sur place, sont venus cautionner cette d\u00e9marche. On peut souhaiter qu&rsquo;il y en ait d&rsquo;autres.<br \/>&nbsp;<\/p>\n<p><strong><\/strong><\/p>\n<div style=\"text-align: center\"><\/div>\n<div style=\"text-align: center\"><a href='https:\/\/archives.rencontrestsiganes.org\/IMG\/jpg\/Fe_te_a_gradanne_3.jpg' type=\"image\/jpeg\" title=\"JPEG - 144 ko\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/archives.rencontrestsiganes.org\/local\/cache-vignettes\/L110xH74\/Fe_te_a_gradanne_3-b668e.jpg?date=1367745801\" style=\"height:74px;width:110px;\" alt=\"\" class=\"miniature_document\" height=\"74\" width=\"110\"><\/a><\/div>\n<div style=\"text-align: center\"><\/div>\n<div><a href='https:\/\/archives.rencontrestsiganes.org\/IMG\/jpg\/Fe_te_a_gardanne_1.jpg' type=\"image\/jpeg\" title=\"JPEG - 135.8 ko\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/archives.rencontrestsiganes.org\/local\/cache-vignettes\/L110xH74\/Fe_te_a_gardanne_1-7aebb.jpg?date=1367745779\" alt=\"\" class=\"miniature_document\" height=\"74\" width=\"110\"><\/a><\/p>\n<div style=\"text-align: center\"><\/div>\n<div style=\"text-align: right;\"><a href='https:\/\/archives.rencontrestsiganes.org\/IMG\/jpg\/Fe_te_a_gardanne_2.jpg' type=\"image\/jpeg\" title=\"JPEG - 190.7 ko\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/archives.rencontrestsiganes.org\/local\/cache-vignettes\/L110xH85\/Fe_te_a_gardanne_2-65232.jpg?date=1367745790\" style=\"height:85px;width:110px;\" alt=\"\" class=\"miniature_document\" height=\"85\" width=\"110\"><\/a><\/div>\n<\/div>\n<p><strong><\/strong><\/p>\n<p style=\"text-align: center;\"><strong><\/strong><a href='https:\/\/archives.rencontrestsiganes.org\/IMG\/jpg\/e_te_a_Gardanne_4.jpg' type=\"image\/jpeg\" title=\"JPEG - 171.2 ko\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/archives.rencontrestsiganes.org\/local\/cache-vignettes\/L110xH74\/e_te_a_Gardanne_4-e31d1.jpg?date=1367745811\" style=\"height:74px;width:110px;\" alt=\"\" class=\"miniature_document\" height=\"74\" width=\"110\"><\/a><\/p>\n<p><strong>La lettre ci dessous re\u00e7ue d&rsquo;un marseillais anonyme redonne aussi un peu d &lsquo;espoir&nbsp;:<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>J habite \u00e0 Marseille, quartier de la Belle de Mai, pr\u00e9cis\u00e9ment la butte Saint-Mauront. C&rsquo;est, selon les statistiques, le quartier le plus pauvre de France, un des plus d\u00e9favoris\u00e9s d&rsquo;Europe. A 50 m\u00e8tres de chez moi sur le boulevard Plombi\u00e8res, sous les autoroutes A7 et A 55 comme vers la Porte d&rsquo;Aix et sur le secteur des Puces aux Arnavaux, des familles Roms vivent depuis 2010 l&rsquo;enfer des pers\u00e9cutions orchestr\u00e9es par la Mairie et par l&rsquo;Etat&nbsp;: destructions des habitations et des biens personnels, expulsions quels que soient la saison, l&rsquo;heure ou la pr\u00e9sence de b\u00e9b\u00e9s, harc\u00e8lements en tous genre, pelleteuses pour retourner les terrains. Comme si cela ne suffisait pas, la municipalit\u00e9, la police et la presse imb\u00e9cile de la droite locale (La Provence par exemple) distillent en permanence le venin stupide, celui du consensus-qui-se-passe-de-toute-r\u00e9flexion&nbsp;: il y a un \u00ab\u00a0probl\u00e8me Rom\u00a0\u00bb \u00e9vident, criant, manifeste, ces gens qui refusent toute int\u00e9gration, sont des voleurs, etc.<br \/><\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/p>\n<p><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Sachez cependant que les probl\u00e8mes de Marseille, bien r\u00e9els, peuvent se hi\u00e9rarchiser sommairement comme suit&nbsp;: 1) Corruption s\u00e9culaire des dirigeants politiques, li\u00e9s \u00e0 la mafia et au grand banditisme depuis au moins 80 ans. Voyez rien que ces jours-ci les proc\u00e9dures Gu\u00e9rini, le proc\u00e8s Andrieux, l&rsquo;affaire des policiers ripoux de la Bac Nord, l&rsquo;arriv\u00e9e en fanfare de Tapie&#8230; Et le client\u00e9lisme \u00e9hont\u00e9, la sp\u00e9culation immobili\u00e8re d\u00e9sastreuse, le surendettement d\u00e9lirant de la ville orchestr\u00e9 par Gaudin, j&rsquo;en passe. 2) Absence totale, en cons\u00e9quence, de politique urbaine un tant soit peu coh\u00e9rente. Les \u00e9normes ou minuscules travaux qui durent des ann\u00e9es et des ann\u00e9es masquent ce d\u00e9sastre structurel. 3) En cons\u00e9quence, un retard d&rsquo;au moins 40 ans sur toutes les infrastructures intercommunales et les services collectifs (transports r\u00e9gionaux, gestion des d\u00e9chets, pollution, politique du logement, financement du tissu \u00e9conomique, espaces verts, lieux culturels, sportifs)&nbsp;: comparez \u00e0 Toulouse, Lyon, et m\u00eame Bordeaux&nbsp;! \u00e0 Nantes, Lille, et m\u00eame Montpellier&nbsp;! 4) Un ch\u00f4mage terrifiant, plus de 40&nbsp;% dans certains quartiers, d&rsquo;o\u00f9 une \u00e9conomie parall\u00e8le et un travail au black qui touchent tous les secteurs d&rsquo;activit\u00e9, pas seulement la drogue&nbsp;: allez payer normalement un artisan \u00e0 Marseille &#8212; je vous parle du bon artisan fran\u00e7ais avec sa jolie soci\u00e9t\u00e9 inscrite au Registre du Commerce&nbsp;: bon courage&nbsp;! Et allez voir dans les restaus sympas du Vieux Port ou sur les chantiers d&rsquo;Euromed, dirig\u00e9s par de bons entrepreneurs marseillais, qui travaille avec un vrai contrat et des papiers en r\u00e8gle&nbsp;?<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/p>\n<p><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>5) Et pour masquer tout \u00e7a, le racisme, le bon vieux racisme aveugle, ang\u00e9lique, qui refuse en bloc de comprendre l&rsquo;histoire de cette ville, industrielle-coloniale, li\u00e9e organiquement \u00e0 l&rsquo;Alg\u00e9rie bien avant 1962, tout autant \u00e0 la Corse, \u00e0 l&rsquo;Italie qu&rsquo;\u00e0 certains pays d&rsquo;Afrique, aux Comores, etc. Les d\u00e9clins industriels, les abandons et d\u00e9labrements urbains de Marseille, dont le patronat local est l&rsquo;\u00e9vident responsable principal depuis 3 ou 4 g\u00e9n\u00e9rations, seront-ils masqu\u00e9s par la constitution en toute h\u00e2te du masque cosm\u00e9tique d&rsquo;une ville-\u00e9tape pour croisi\u00e8res de r\u00eave&nbsp;? \u00e0 voir.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/p>\n<p><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Les Roms dans tout \u00e7a&nbsp;? Les derniers venus, ceux sur qui tout le monde s&rsquo;entend pour taper, jusque dans les quartiers mis\u00e9rables du Nord de la ville.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/p>\n<p><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Cambriol\u00e9 une fois en 2 ans (une bonne moyenne), l&rsquo;ai-je \u00e9t\u00e9 par des Roms&nbsp;? ben non&nbsp;! Ma voiture br\u00fbl\u00e9e en d\u00e9cembre&nbsp;: par des Roms&nbsp;? ben non&nbsp;! Mes probl\u00e8mes quotidiens \u00e0 Marseille, la faute aux Roms&nbsp;? Mille fois non, \u00e9videmment&nbsp;! Et je serais bien con de croire en une diversion pareille&nbsp;!<\/em><\/p>\n<p style=\"text-align: justify;\"><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/p>\n<p><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p><em><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Les Roms, minorit\u00e9 infime et population des plus vuln\u00e9rables, ne posent rigoureusement aucun probl\u00e8me \u00e0 cette ville que l&rsquo;on ne puisse r\u00e9soudre avec un petit peu de bon sens et de moyens. Ils sont simplement bien pratiques en ce moment pour \u00ab\u00a0expliquer\u00a0\u00bb la merde dans laquelle la France s&rsquo;enfonce. Cette merde, elle d\u00e9gouline d&rsquo;ailleurs et de bien plus haut que des campements Roms<br \/><\/em><\/p>\n<p style=\"text-align: justify;\"><em>&nbsp;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les conditions  de vie indignes des Roms entrainent la multiplication des conflits de voisinages qui risquent \u00e0 tout instant de tourner au drame  avec parfois la complicit\u00e9 des \u00e9lus.     <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1145","post","type-post","status-publish","format-standard","hentry","category-migrants-roms"],"_links":{"self":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/comments?post=1145"}],"version-history":[{"count":0,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/posts\/1145\/revisions"}],"wp:attachment":[{"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/media?parent=1145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/categories?post=1145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archives.rencontrestsiganes.org\/index.php\/wp-json\/wp\/v2\/tags?post=1145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}